{"id":15765,"date":"2016-12-11T17:06:16","date_gmt":"2016-12-11T16:06:16","guid":{"rendered":"https:\/\/galleriamichelarizzo.it\/publications\/"},"modified":"2016-12-11T17:06:16","modified_gmt":"2016-12-11T16:06:16","slug":"publications","status":"publish","type":"page","link":"https:\/\/galleriamichelarizzo.it\/en\/publications\/","title":{"rendered":"Pubblicazioni"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-pubblicazioni.php","meta":[],"_links":{"self":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/pages\/15765"}],"collection":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/comments?post=15765"}],"version-history":[{"count":0,"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/pages\/15765\/revisions"}],"wp:attachment":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/media?parent=15765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}