{"id":210,"count":2,"description":"","link":"https:\/\/galleriamichelarizzo.it\/en\/category\/romano-lotto-en\/","name":"Romano Lotto","slug":"romano-lotto-en","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/categories\/210"}],"collection":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/posts?categories=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}