{"id":136,"count":8,"description":"","link":"https:\/\/galleriamichelarizzo.it\/en\/category\/maurizio-pellegrin-en\/","name":"Maurizio Pellegrin","slug":"maurizio-pellegrin-en","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/categories\/136"}],"collection":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/galleriamichelarizzo.it\/en\/wp-json\/wp\/v2\/posts?categories=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}